{"id":9331,"date":"2025-05-13T08:12:52","date_gmt":"2025-05-13T08:12:52","guid":{"rendered":"https:\/\/kjpetshop.com\/?post_type=product&#038;p=9331"},"modified":"2026-01-24T11:26:23","modified_gmt":"2026-01-24T04:26:23","slug":"kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2","status":"publish","type":"product","link":"https:\/\/kjpetshop.com\/en\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/","title":{"rendered":"Kaniva Pouch \u0e04\u0e32\u0e19\u0e34\u0e27\u0e48\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e01\u0e30 \u0e43\u0e19\u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 70g."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Kaniva \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1b\u0e35\u0e22\u0e01\u0e41\u0e21\u0e27\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e38\u0e14\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2a\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e32\u0e07\u0e40\u0e23\u0e32\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e21\u0e27 \u201c\u0e02\u0e19\u0e2a\u0e27\u0e22 \u0e40\u0e07\u0e32\u0e07\u0e32\u0e21 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u201d<\/p>\n<p>\u0e17\u0e27\u0e35\u0e04\u0e39\u0e13\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e40\u0e2b\u0e21\u0e35\u0e22\u0e27\u0e14\u0e49\u0e27\u0e22\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e2b\u0e25\u0e31\u0e01 \u0e21\u0e35\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e2a\u0e39\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d<\/p>\n<p>\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e1a\u0e2d\u0e25\u0e2d\u0e38\u0e14\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e2d\u0e07\u0e41\u0e21\u0e27\u0e0a\u0e48\u0e27\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e21\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e20\u0e39\u0e21\u0e34\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e19 \u0e44\u0e21\u0e48\u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e25\u0e37\u0e2d<\/p>\n<p>\u0e1b\u0e23\u0e32\u0e28\u0e08\u0e32\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e25\u0e35\u0e41\u0e25\u0e30\u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e2d\u0e38\u0e14\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2a\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e21\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22<\/p>","protected":false},"featured_media":19208,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[522],"product_cat":[940,942],"product_tag":[],"class_list":{"0":"post-9331","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-kaniva","7":"product_cat-cat","8":"product_cat-942","9":"pa_-1-","12":"first","13":"outofstock","14":"purchasable","15":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kaniva Pouch \u0e04\u0e32\u0e19\u0e34\u0e27\u0e48\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e01\u0e30 \u0e43\u0e19\u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 70g. - Khaojao Pet Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kjpetshop.com\/en\/product\/kaniva-pouch-\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01-\u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kaniva Pouch \u0e04\u0e32\u0e19\u0e34\u0e27\u0e48\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e01\u0e30 \u0e43\u0e19\u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 70g. - Khaojao Pet Shop\" \/>\n<meta property=\"og:description\" content=\"Kaniva \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1b\u0e35\u0e22\u0e01\u0e41\u0e21\u0e27\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e38\u0e14\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2a\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e32\u0e07\u0e40\u0e23\u0e32\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e21\u0e27 \u201c\u0e02\u0e19\u0e2a\u0e27\u0e22 \u0e40\u0e07\u0e32\u0e07\u0e32\u0e21 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u201d  \u0e17\u0e27\u0e35\u0e04\u0e39\u0e13\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e40\u0e2b\u0e21\u0e35\u0e22\u0e27\u0e14\u0e49\u0e27\u0e22\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e2b\u0e25\u0e31\u0e01 \u0e21\u0e35\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e2a\u0e39\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d  \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e1a\u0e2d\u0e25\u0e2d\u0e38\u0e14\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e2d\u0e07\u0e41\u0e21\u0e27\u0e0a\u0e48\u0e27\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e21\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e20\u0e39\u0e21\u0e34\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e19 \u0e44\u0e21\u0e48\u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e25\u0e37\u0e2d  \u0e1b\u0e23\u0e32\u0e28\u0e08\u0e32\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e25\u0e35\u0e41\u0e25\u0e30\u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e2d\u0e38\u0e14\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2a\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e21\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kjpetshop.com\/en\/product\/kaniva-pouch-\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01-\u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Khaojao Pet Shop\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-24T04:26:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/05\/1-54-19.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/\",\"url\":\"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/\",\"name\":\"Kaniva Pouch \u0e04\u0e32\u0e19\u0e34\u0e27\u0e48\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e01\u0e30 \u0e43\u0e19\u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 70g. - Khaojao Pet Shop\",\"isPartOf\":{\"@id\":\"https:\/\/kjpetshop.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/05\/1-54-19.webp\",\"datePublished\":\"2025-05-13T08:12:52+00:00\",\"dateModified\":\"2026-01-24T04:26:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/#primaryimage\",\"url\":\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/05\/1-54-19.webp\",\"contentUrl\":\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/05\/1-54-19.webp\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kjpetshop.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\",\"item\":\"https:\/\/kjpetshop.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kaniva Pouch \u0e04\u0e32\u0e19\u0e34\u0e27\u0e48\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e01\u0e30 \u0e43\u0e19\u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 70g.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kjpetshop.com\/#website\",\"url\":\"https:\/\/kjpetshop.com\/\",\"name\":\"Khaojao Pet Shop\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/kjpetshop.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kjpetshop.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kjpetshop.com\/#organization\",\"name\":\"Khaojao Pet Shop\",\"url\":\"https:\/\/kjpetshop.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/kjpetshop.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/03\/bb2786d6-19b3-4605-9fc4-ace05fe45e03-e1742700039668.png\",\"contentUrl\":\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/03\/bb2786d6-19b3-4605-9fc4-ace05fe45e03-e1742700039668.png\",\"width\":300,\"height\":300,\"caption\":\"Khaojao Pet Shop\"},\"image\":{\"@id\":\"https:\/\/kjpetshop.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kaniva Pouch \u0e04\u0e32\u0e19\u0e34\u0e27\u0e48\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e01\u0e30 \u0e43\u0e19\u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 70g. - Khaojao Pet Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kjpetshop.com\/en\/product\/kaniva-pouch-\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01-\u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48-2\/","og_locale":"en_US","og_type":"article","og_title":"Kaniva Pouch \u0e04\u0e32\u0e19\u0e34\u0e27\u0e48\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e01\u0e30 \u0e43\u0e19\u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 70g. - Khaojao Pet Shop","og_description":"Kaniva \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1b\u0e35\u0e22\u0e01\u0e41\u0e21\u0e27\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e38\u0e14\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2a\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e32\u0e07\u0e40\u0e23\u0e32\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e21\u0e27 \u201c\u0e02\u0e19\u0e2a\u0e27\u0e22 \u0e40\u0e07\u0e32\u0e07\u0e32\u0e21 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u201d  \u0e17\u0e27\u0e35\u0e04\u0e39\u0e13\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e40\u0e2b\u0e21\u0e35\u0e22\u0e27\u0e14\u0e49\u0e27\u0e22\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e2b\u0e25\u0e31\u0e01 \u0e21\u0e35\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e2a\u0e39\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d  \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e1a\u0e2d\u0e25\u0e2d\u0e38\u0e14\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e2d\u0e07\u0e41\u0e21\u0e27\u0e0a\u0e48\u0e27\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e21\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e20\u0e39\u0e21\u0e34\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e19 \u0e44\u0e21\u0e48\u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e25\u0e37\u0e2d  \u0e1b\u0e23\u0e32\u0e28\u0e08\u0e32\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e25\u0e35\u0e41\u0e25\u0e30\u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e2d\u0e38\u0e14\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e2a\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e21\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22","og_url":"https:\/\/kjpetshop.com\/en\/product\/kaniva-pouch-\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01-\u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48-2\/","og_site_name":"Khaojao Pet Shop","article_modified_time":"2026-01-24T04:26:23+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/05\/1-54-19.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/","url":"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/","name":"Kaniva Pouch \u0e04\u0e32\u0e19\u0e34\u0e27\u0e48\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e01\u0e30 \u0e43\u0e19\u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 70g. - Khaojao Pet Shop","isPartOf":{"@id":"https:\/\/kjpetshop.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/#primaryimage"},"image":{"@id":"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/#primaryimage"},"thumbnailUrl":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/05\/1-54-19.webp","datePublished":"2025-05-13T08:12:52+00:00","dateModified":"2026-01-24T04:26:23+00:00","breadcrumb":{"@id":"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/#primaryimage","url":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/05\/1-54-19.webp","contentUrl":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/05\/1-54-19.webp","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/kjpetshop.com\/product\/kaniva-pouch-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a1%e0%b8%a7%e0%b9%80%e0%b8%9b%e0%b8%b5%e0%b8%a2%e0%b8%81-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%97%e0%b8%b9%e0%b8%99%e0%b9%88-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kjpetshop.com\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14","item":"https:\/\/kjpetshop.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Kaniva Pouch \u0e04\u0e32\u0e19\u0e34\u0e27\u0e48\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e1b\u0e25\u0e32\u0e17\u0e39\u0e19\u0e48\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e01\u0e30 \u0e43\u0e19\u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 70g."}]},{"@type":"WebSite","@id":"https:\/\/kjpetshop.com\/#website","url":"https:\/\/kjpetshop.com\/","name":"Khaojao Pet Shop","description":"","publisher":{"@id":"https:\/\/kjpetshop.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kjpetshop.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kjpetshop.com\/#organization","name":"Khaojao Pet Shop","url":"https:\/\/kjpetshop.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kjpetshop.com\/#\/schema\/logo\/image\/","url":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/03\/bb2786d6-19b3-4605-9fc4-ace05fe45e03-e1742700039668.png","contentUrl":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/03\/bb2786d6-19b3-4605-9fc4-ace05fe45e03-e1742700039668.png","width":300,"height":300,"caption":"Khaojao Pet Shop"},"image":{"@id":"https:\/\/kjpetshop.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product\/9331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/comments?post=9331"}],"version-history":[{"count":2,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product\/9331\/revisions"}],"predecessor-version":[{"id":14069,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product\/9331\/revisions\/14069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/media\/19208"}],"wp:attachment":[{"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/media?parent=9331"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product_brand?post=9331"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product_cat?post=9331"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product_tag?post=9331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}