{"id":17186,"date":"2025-06-21T11:29:19","date_gmt":"2025-06-21T11:29:19","guid":{"rendered":"https:\/\/kjpetshop.com\/?post_type=product&#038;p=17186"},"modified":"2026-02-01T15:55:46","modified_gmt":"2026-02-01T08:55:46","slug":"me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95","status":"publish","type":"product","link":"https:\/\/kjpetshop.com\/en\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/","title":{"rendered":"Me-o Gold Persian \u0e21\u0e35\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e21\u0e27\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22 \u0e2a\u0e39\u0e15\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e02\u0e19 7Kg."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e21\u0e27\u0e42\u0e15\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22\u0e41\u0e25\u0e30\u0e41\u0e21\u0e27\u0e02\u0e19\u0e22\u0e32\u0e27\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c<\/p>\n<p>\u0e2d\u0e35\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32\u0e40\u0e2b\u0e21\u0e35\u0e22\u0e27<\/p>\n<p>\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d<\/p>\n<p>\u2022 \u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e08\u0e32\u0e01\u0e44\u0e01\u0e48\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07<\/p>\n<p>\u2022 \u0e21\u0e35\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e1a\u0e40\u0e2e\u0e23\u0e15\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27 \u0e0b\u0e36\u0e48\u0e07\u0e22\u0e48\u0e2d\u0e22\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e39\u0e14\u0e0b\u0e36\u0e21\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e44\u0e14\u0e49\u0e14\u0e35<\/p>\n<p>\u2022 \u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e01\u0e49\u0e2d\u0e19\u0e02\u0e19\u0e2d\u0e38\u0e14\u0e15\u0e31\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e02\u0e31\u0e1a\u0e01\u0e49\u0e2d\u0e19\u0e02\u0e19\u0e43\u0e2b\u0e49\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e21\u0e39\u0e25 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e43\u0e22\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34<\/p>\n<p>\u2022 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e31\u0e07\u0e21\u0e35\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e41\u0e25\u0e30\u0e02\u0e19\u0e40\u0e07\u0e32\u0e07\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e42\u0e2d\u0e40\u0e21\u0e01\u0e49\u0e32 3 \u0e42\u0e2d\u0e40\u0e21\u0e01\u0e49\u0e32 6 \u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35<\/p>\n<p>\u2022 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e14\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e35\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01 (\u0e1f\u0e23\u0e38\u0e01\u0e42\u0e15-\u0e42\u0e2d\u0e25\u0e34\u0e42\u0e01\u0e41\u0e0b\u0e04\u0e04\u0e32\u0e44\u0e23\u0e14\u0e4c)<\/p>\n<p>\u2022 \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e19\u0e43\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e21\u0e27\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e0b\u0e35<\/p>\n<p>\u2022 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e23\u0e30\u0e14\u0e39\u0e01\u0e41\u0e25\u0e30\u0e1f\u0e31\u0e19\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e41\u0e04\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e21 \u0e1f\u0e2d\u0e2a\u0e1f\u0e2d\u0e23\u0e31\u0e2a \u0e41\u0e25\u0e30\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e14\u0e35<\/p>\n<p>\u2022 \u0e0a\u0e48\u0e27\u0e22\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e17\u0e2d\u0e23\u0e35\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e41\u0e21\u0e27<\/p>","protected":false},"featured_media":19719,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[1307],"product_cat":[940,1285,941],"product_tag":[],"class_list":{"0":"post-17186","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-me-o-gold","7":"product_cat-cat","8":"product_cat-1285","9":"product_cat-941","11":"first","12":"outofstock","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Me-o Gold Persian \u0e21\u0e35\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e21\u0e27\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22 \u0e2a\u0e39\u0e15\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e02\u0e19 7Kg. - Khaojao Pet Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kjpetshop.com\/en\/product\/me-o-gold-persian-\u0e21\u0e35\u0e42\u0e2d-\u0e42\u0e01\u0e25-\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22-\u0e2a\u0e39\u0e15\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Me-o Gold Persian \u0e21\u0e35\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e21\u0e27\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22 \u0e2a\u0e39\u0e15\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e02\u0e19 7Kg. - Khaojao Pet Shop\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e21\u0e27\u0e42\u0e15\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22\u0e41\u0e25\u0e30\u0e41\u0e21\u0e27\u0e02\u0e19\u0e22\u0e32\u0e27\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c  \u0e2d\u0e35\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32\u0e40\u0e2b\u0e21\u0e35\u0e22\u0e27  \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d  \u2022 \u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e08\u0e32\u0e01\u0e44\u0e01\u0e48\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07  \u2022 \u0e21\u0e35\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e1a\u0e40\u0e2e\u0e23\u0e15\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27 \u0e0b\u0e36\u0e48\u0e07\u0e22\u0e48\u0e2d\u0e22\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e39\u0e14\u0e0b\u0e36\u0e21\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e44\u0e14\u0e49\u0e14\u0e35  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e01\u0e49\u0e2d\u0e19\u0e02\u0e19\u0e2d\u0e38\u0e14\u0e15\u0e31\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e02\u0e31\u0e1a\u0e01\u0e49\u0e2d\u0e19\u0e02\u0e19\u0e43\u0e2b\u0e49\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e21\u0e39\u0e25 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e43\u0e22\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e31\u0e07\u0e21\u0e35\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e41\u0e25\u0e30\u0e02\u0e19\u0e40\u0e07\u0e32\u0e07\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e42\u0e2d\u0e40\u0e21\u0e01\u0e49\u0e32 3 \u0e42\u0e2d\u0e40\u0e21\u0e01\u0e49\u0e32 6 \u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e14\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e35\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01 (\u0e1f\u0e23\u0e38\u0e01\u0e42\u0e15-\u0e42\u0e2d\u0e25\u0e34\u0e42\u0e01\u0e41\u0e0b\u0e04\u0e04\u0e32\u0e44\u0e23\u0e14\u0e4c)  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e19\u0e43\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e21\u0e27\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e0b\u0e35  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e23\u0e30\u0e14\u0e39\u0e01\u0e41\u0e25\u0e30\u0e1f\u0e31\u0e19\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e41\u0e04\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e21 \u0e1f\u0e2d\u0e2a\u0e1f\u0e2d\u0e23\u0e31\u0e2a \u0e41\u0e25\u0e30\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e14\u0e35  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e17\u0e2d\u0e23\u0e35\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e41\u0e21\u0e27\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kjpetshop.com\/en\/product\/me-o-gold-persian-\u0e21\u0e35\u0e42\u0e2d-\u0e42\u0e01\u0e25-\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22-\u0e2a\u0e39\u0e15\/\" \/>\n<meta property=\"og:site_name\" content=\"Khaojao Pet Shop\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-01T08:55:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/06\/001-61.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/\",\"url\":\"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/\",\"name\":\"Me-o Gold Persian \u0e21\u0e35\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e21\u0e27\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22 \u0e2a\u0e39\u0e15\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e02\u0e19 7Kg. - Khaojao Pet Shop\",\"isPartOf\":{\"@id\":\"https:\/\/kjpetshop.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/06\/001-61.webp\",\"datePublished\":\"2025-06-21T11:29:19+00:00\",\"dateModified\":\"2026-02-01T08:55:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/#primaryimage\",\"url\":\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/06\/001-61.webp\",\"contentUrl\":\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/06\/001-61.webp\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kjpetshop.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\",\"item\":\"https:\/\/kjpetshop.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Me-o Gold Persian \u0e21\u0e35\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e21\u0e27\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22 \u0e2a\u0e39\u0e15\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e02\u0e19 7Kg.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kjpetshop.com\/#website\",\"url\":\"https:\/\/kjpetshop.com\/\",\"name\":\"Khaojao Pet Shop\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/kjpetshop.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kjpetshop.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kjpetshop.com\/#organization\",\"name\":\"Khaojao Pet Shop\",\"url\":\"https:\/\/kjpetshop.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/kjpetshop.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/03\/bb2786d6-19b3-4605-9fc4-ace05fe45e03-e1742700039668.png\",\"contentUrl\":\"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/03\/bb2786d6-19b3-4605-9fc4-ace05fe45e03-e1742700039668.png\",\"width\":300,\"height\":300,\"caption\":\"Khaojao Pet Shop\"},\"image\":{\"@id\":\"https:\/\/kjpetshop.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Me-o Gold Persian \u0e21\u0e35\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e21\u0e27\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22 \u0e2a\u0e39\u0e15\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e02\u0e19 7Kg. - Khaojao Pet Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kjpetshop.com\/en\/product\/me-o-gold-persian-\u0e21\u0e35\u0e42\u0e2d-\u0e42\u0e01\u0e25-\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22-\u0e2a\u0e39\u0e15\/","og_locale":"en_US","og_type":"article","og_title":"Me-o Gold Persian \u0e21\u0e35\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e21\u0e27\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22 \u0e2a\u0e39\u0e15\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e02\u0e19 7Kg. - Khaojao Pet Shop","og_description":"\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e21\u0e27\u0e42\u0e15\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22\u0e41\u0e25\u0e30\u0e41\u0e21\u0e27\u0e02\u0e19\u0e22\u0e32\u0e27\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c  \u0e2d\u0e35\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32\u0e40\u0e2b\u0e21\u0e35\u0e22\u0e27  \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d  \u2022 \u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e08\u0e32\u0e01\u0e44\u0e01\u0e48\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07  \u2022 \u0e21\u0e35\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e1a\u0e40\u0e2e\u0e23\u0e15\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27 \u0e0b\u0e36\u0e48\u0e07\u0e22\u0e48\u0e2d\u0e22\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e39\u0e14\u0e0b\u0e36\u0e21\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e44\u0e14\u0e49\u0e14\u0e35  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e01\u0e49\u0e2d\u0e19\u0e02\u0e19\u0e2d\u0e38\u0e14\u0e15\u0e31\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e02\u0e31\u0e1a\u0e01\u0e49\u0e2d\u0e19\u0e02\u0e19\u0e43\u0e2b\u0e49\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e21\u0e39\u0e25 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e43\u0e22\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e31\u0e07\u0e21\u0e35\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e41\u0e25\u0e30\u0e02\u0e19\u0e40\u0e07\u0e32\u0e07\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e42\u0e2d\u0e40\u0e21\u0e01\u0e49\u0e32 3 \u0e42\u0e2d\u0e40\u0e21\u0e01\u0e49\u0e32 6 \u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e35 \u0e14\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e35\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01 (\u0e1f\u0e23\u0e38\u0e01\u0e42\u0e15-\u0e42\u0e2d\u0e25\u0e34\u0e42\u0e01\u0e41\u0e0b\u0e04\u0e04\u0e32\u0e44\u0e23\u0e14\u0e4c)  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e19\u0e43\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e21\u0e27\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e0b\u0e35  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e23\u0e30\u0e14\u0e39\u0e01\u0e41\u0e25\u0e30\u0e1f\u0e31\u0e19\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e41\u0e04\u0e25\u0e40\u0e0b\u0e35\u0e22\u0e21 \u0e1f\u0e2d\u0e2a\u0e1f\u0e2d\u0e23\u0e31\u0e2a \u0e41\u0e25\u0e30\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e14\u0e35  \u2022 \u0e0a\u0e48\u0e27\u0e22\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e17\u0e2d\u0e23\u0e35\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e41\u0e21\u0e27","og_url":"https:\/\/kjpetshop.com\/en\/product\/me-o-gold-persian-\u0e21\u0e35\u0e42\u0e2d-\u0e42\u0e01\u0e25-\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22-\u0e2a\u0e39\u0e15\/","og_site_name":"Khaojao Pet Shop","article_modified_time":"2026-02-01T08:55:46+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/06\/001-61.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/","url":"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/","name":"Me-o Gold Persian \u0e21\u0e35\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e21\u0e27\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22 \u0e2a\u0e39\u0e15\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e02\u0e19 7Kg. - Khaojao Pet Shop","isPartOf":{"@id":"https:\/\/kjpetshop.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/#primaryimage"},"image":{"@id":"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/#primaryimage"},"thumbnailUrl":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/06\/001-61.webp","datePublished":"2025-06-21T11:29:19+00:00","dateModified":"2026-02-01T08:55:46+00:00","breadcrumb":{"@id":"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/#primaryimage","url":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/06\/001-61.webp","contentUrl":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/06\/001-61.webp","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/kjpetshop.com\/product\/me-o-gold-persian-%e0%b8%a1%e0%b8%b5%e0%b9%82%e0%b8%ad-%e0%b9%82%e0%b8%81%e0%b8%a5-%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%aa%e0%b8%b9%e0%b8%95\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kjpetshop.com\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14","item":"https:\/\/kjpetshop.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Me-o Gold Persian \u0e21\u0e35\u0e42\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e21\u0e27\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e35\u0e22 \u0e2a\u0e39\u0e15\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e02\u0e19 7Kg."}]},{"@type":"WebSite","@id":"https:\/\/kjpetshop.com\/#website","url":"https:\/\/kjpetshop.com\/","name":"Khaojao Pet Shop","description":"","publisher":{"@id":"https:\/\/kjpetshop.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kjpetshop.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kjpetshop.com\/#organization","name":"Khaojao Pet Shop","url":"https:\/\/kjpetshop.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kjpetshop.com\/#\/schema\/logo\/image\/","url":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/03\/bb2786d6-19b3-4605-9fc4-ace05fe45e03-e1742700039668.png","contentUrl":"https:\/\/kjpetshop.com\/wp-content\/uploads\/2025\/03\/bb2786d6-19b3-4605-9fc4-ace05fe45e03-e1742700039668.png","width":300,"height":300,"caption":"Khaojao Pet Shop"},"image":{"@id":"https:\/\/kjpetshop.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product\/17186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/comments?post=17186"}],"version-history":[{"count":3,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product\/17186\/revisions"}],"predecessor-version":[{"id":17408,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product\/17186\/revisions\/17408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/media\/19719"}],"wp:attachment":[{"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/media?parent=17186"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product_brand?post=17186"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product_cat?post=17186"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kjpetshop.com\/en\/wp-json\/wp\/v2\/product_tag?post=17186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}